{"id":18661,"date":"2020-06-15T10:56:23","date_gmt":"2020-06-15T10:56:23","guid":{"rendered":"https:\/\/www.healthbenefitstimes.com\/glossary\/?p=18661"},"modified":"2020-06-15T10:56:23","modified_gmt":"2020-06-15T10:56:23","slug":"plumulose","status":"publish","type":"post","link":"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/","title":{"rendered":"Plumulose"},"content":{"rendered":"<p>A little plumose [unusual term].<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A little plumose [unusual term]. &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-18661","post","type-post","status-publish","format-standard","hentry","category-p"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plumulose - Definition of Plumulose<\/title>\n<meta name=\"description\" content=\"A little plumose [unusual term].\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plumulose - Definition of Plumulose\" \/>\n<meta property=\"og:description\" content=\"A little plumose [unusual term].\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/\" \/>\n<meta property=\"og:site_name\" content=\"Glossary\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-15T10:56:23+00:00\" \/>\n<meta name=\"author\" content=\"Glossary\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glossary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/\",\"url\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/\",\"name\":\"Plumulose - Definition of Plumulose\",\"isPartOf\":{\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#website\"},\"datePublished\":\"2020-06-15T10:56:23+00:00\",\"dateModified\":\"2020-06-15T10:56:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5\"},\"description\":\"A little plumose [unusual term].\",\"breadcrumb\":{\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plumulose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#website\",\"url\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/\",\"name\":\"Glossary\",\"description\":\"Difinitions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5\",\"name\":\"Glossary\",\"url\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/author\/adminglossary\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plumulose - Definition of Plumulose","description":"A little plumose [unusual term].","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/","og_locale":"en_US","og_type":"article","og_title":"Plumulose - Definition of Plumulose","og_description":"A little plumose [unusual term].","og_url":"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/","og_site_name":"Glossary","article_published_time":"2020-06-15T10:56:23+00:00","author":"Glossary","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Glossary"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/","url":"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/","name":"Plumulose - Definition of Plumulose","isPartOf":{"@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#website"},"datePublished":"2020-06-15T10:56:23+00:00","dateModified":"2020-06-15T10:56:23+00:00","author":{"@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5"},"description":"A little plumose [unusual term].","breadcrumb":{"@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/plumulose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.healthbenefitstimes.com\/glossary\/"},{"@type":"ListItem","position":2,"name":"Plumulose"}]},{"@type":"WebSite","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#website","url":"https:\/\/www.healthbenefitstimes.com\/glossary\/","name":"Glossary","description":"Difinitions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.healthbenefitstimes.com\/glossary\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5","name":"Glossary","url":"https:\/\/www.healthbenefitstimes.com\/glossary\/author\/adminglossary\/"}]}},"_links":{"self":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts\/18661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/comments?post=18661"}],"version-history":[{"count":1,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts\/18661\/revisions"}],"predecessor-version":[{"id":18662,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts\/18661\/revisions\/18662"}],"wp:attachment":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/media?parent=18661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/categories?post=18661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/tags?post=18661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}