{"id":225387,"date":"2023-05-21T05:16:45","date_gmt":"2023-05-21T05:16:45","guid":{"rendered":"https:\/\/www.healthbenefitstimes.com\/glossary\/?p=225387"},"modified":"2023-05-21T05:16:45","modified_gmt":"2023-05-21T05:16:45","slug":"exposure-dose-rate","status":"publish","type":"post","link":"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/","title":{"rendered":"Exposure-dose rate"},"content":{"rendered":"<p>The exposure dose per unit time. The unit of exposure-dose rate is the roentgen per unit time.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The exposure dose per unit time. The unit of exposure-dose rate is the roentgen per unit time.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-225387","post","type-post","status-publish","format-standard","hentry","category-e"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exposure-dose rate - Definition of Exposure-dose rate<\/title>\n<meta name=\"description\" content=\"The exposure dose per unit time. The unit of exposure-dose rate is the roentgen per unit time.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposure-dose rate - Definition of Exposure-dose rate\" \/>\n<meta property=\"og:description\" content=\"The exposure dose per unit time. The unit of exposure-dose rate is the roentgen per unit time.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/\" \/>\n<meta property=\"og:site_name\" content=\"Glossary\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-21T05:16:45+00:00\" \/>\n<meta name=\"author\" content=\"Glossary\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glossary\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/\",\"url\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/\",\"name\":\"Exposure-dose rate - Definition of Exposure-dose rate\",\"isPartOf\":{\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#website\"},\"datePublished\":\"2023-05-21T05:16:45+00:00\",\"dateModified\":\"2023-05-21T05:16:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5\"},\"description\":\"The exposure dose per unit time. The unit of exposure-dose rate is the roentgen per unit time.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exposure-dose rate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#website\",\"url\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/\",\"name\":\"Glossary\",\"description\":\"Difinitions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5\",\"name\":\"Glossary\",\"url\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/author\/adminglossary\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposure-dose rate - Definition of Exposure-dose rate","description":"The exposure dose per unit time. The unit of exposure-dose rate is the roentgen per unit time.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/","og_locale":"en_US","og_type":"article","og_title":"Exposure-dose rate - Definition of Exposure-dose rate","og_description":"The exposure dose per unit time. The unit of exposure-dose rate is the roentgen per unit time.","og_url":"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/","og_site_name":"Glossary","article_published_time":"2023-05-21T05:16:45+00:00","author":"Glossary","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Glossary","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/","url":"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/","name":"Exposure-dose rate - Definition of Exposure-dose rate","isPartOf":{"@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#website"},"datePublished":"2023-05-21T05:16:45+00:00","dateModified":"2023-05-21T05:16:45+00:00","author":{"@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5"},"description":"The exposure dose per unit time. The unit of exposure-dose rate is the roentgen per unit time.","breadcrumb":{"@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/exposure-dose-rate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.healthbenefitstimes.com\/glossary\/"},{"@type":"ListItem","position":2,"name":"Exposure-dose rate"}]},{"@type":"WebSite","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#website","url":"https:\/\/www.healthbenefitstimes.com\/glossary\/","name":"Glossary","description":"Difinitions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.healthbenefitstimes.com\/glossary\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5","name":"Glossary","url":"https:\/\/www.healthbenefitstimes.com\/glossary\/author\/adminglossary\/"}]}},"_links":{"self":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts\/225387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/comments?post=225387"}],"version-history":[{"count":1,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts\/225387\/revisions"}],"predecessor-version":[{"id":225388,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts\/225387\/revisions\/225388"}],"wp:attachment":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/media?parent=225387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/categories?post=225387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/tags?post=225387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}