{"id":78346,"date":"2021-01-22T04:59:18","date_gmt":"2021-01-22T04:59:18","guid":{"rendered":"https:\/\/www.healthbenefitstimes.com\/glossary\/?p=78346"},"modified":"2021-01-22T05:00:24","modified_gmt":"2021-01-22T05:00:24","slug":"iliopelvic","status":"publish","type":"post","link":"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/","title":{"rendered":"Iliopelvic"},"content":{"rendered":"<p>Flank and pelvis.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flank and pelvis. &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-78346","post","type-post","status-publish","format-standard","hentry","category-i"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Iliopelvic - Definition of Iliopelvic<\/title>\n<meta name=\"description\" content=\"Flank and pelvis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iliopelvic - Definition of Iliopelvic\" \/>\n<meta property=\"og:description\" content=\"Flank and pelvis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/\" \/>\n<meta property=\"og:site_name\" content=\"Glossary\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-22T04:59:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-22T05:00:24+00:00\" \/>\n<meta name=\"author\" content=\"Glossary\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glossary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/\",\"url\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/\",\"name\":\"Iliopelvic - Definition of Iliopelvic\",\"isPartOf\":{\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#website\"},\"datePublished\":\"2021-01-22T04:59:18+00:00\",\"dateModified\":\"2021-01-22T05:00:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5\"},\"description\":\"Flank and pelvis.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iliopelvic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#website\",\"url\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/\",\"name\":\"Glossary\",\"description\":\"Difinitions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5\",\"name\":\"Glossary\",\"url\":\"https:\/\/www.healthbenefitstimes.com\/glossary\/author\/adminglossary\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iliopelvic - Definition of Iliopelvic","description":"Flank and pelvis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/","og_locale":"en_US","og_type":"article","og_title":"Iliopelvic - Definition of Iliopelvic","og_description":"Flank and pelvis.","og_url":"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/","og_site_name":"Glossary","article_published_time":"2021-01-22T04:59:18+00:00","article_modified_time":"2021-01-22T05:00:24+00:00","author":"Glossary","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Glossary"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/","url":"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/","name":"Iliopelvic - Definition of Iliopelvic","isPartOf":{"@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#website"},"datePublished":"2021-01-22T04:59:18+00:00","dateModified":"2021-01-22T05:00:24+00:00","author":{"@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5"},"description":"Flank and pelvis.","breadcrumb":{"@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/iliopelvic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.healthbenefitstimes.com\/glossary\/"},{"@type":"ListItem","position":2,"name":"Iliopelvic"}]},{"@type":"WebSite","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#website","url":"https:\/\/www.healthbenefitstimes.com\/glossary\/","name":"Glossary","description":"Difinitions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.healthbenefitstimes.com\/glossary\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.healthbenefitstimes.com\/glossary\/#\/schema\/person\/ccfef987a4882e6356ae6d77d33e74c5","name":"Glossary","url":"https:\/\/www.healthbenefitstimes.com\/glossary\/author\/adminglossary\/"}]}},"_links":{"self":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts\/78346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/comments?post=78346"}],"version-history":[{"count":1,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts\/78346\/revisions"}],"predecessor-version":[{"id":78347,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/posts\/78346\/revisions\/78347"}],"wp:attachment":[{"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/media?parent=78346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/categories?post=78346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.healthbenefitstimes.com\/glossary\/wp-json\/wp\/v2\/tags?post=78346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}